{"id":175,"count":2,"description":"","link":"https:\/\/continentaldocs.com\/cs\/category\/certificates\/","name":"Certificates","slug":"certificates","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.6 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Certificates Archives | We Are The Best<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/continentaldocs.com\/cs\/category\/certificates\/\" \/>\n<meta property=\"og:locale\" content=\"cs_CZ\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Certificates Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/continentaldocs.com\/cs\/category\/certificates\/\" \/>\n<meta property=\"og:site_name\" content=\"We Are The Best\" \/>\n<meta property=\"og:image\" content=\"https:\/\/continentaldocs.com\/wp-content\/uploads\/2024\/08\/6318f3bb-2715-455d-b41c-f730e9f53b8b.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"458\" \/>\n\t<meta property=\"og:image:height\" content=\"353\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/continentaldocs.com\\\/category\\\/certificates\\\/\",\"url\":\"https:\\\/\\\/continentaldocs.com\\\/category\\\/certificates\\\/\",\"name\":\"Certificates Archives | We Are The Best\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/continentaldocs.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/continentaldocs.com\\\/category\\\/certificates\\\/#breadcrumb\"},\"inLanguage\":\"cs\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/continentaldocs.com\\\/category\\\/certificates\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/continentaldocs.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Certificates\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/continentaldocs.com\\\/#website\",\"url\":\"https:\\\/\\\/continentaldocs.com\\\/\",\"name\":\"Continental Documents Online\",\"description\":\"Continental difference is not a barrier to our services.\",\"publisher\":{\"@id\":\"https:\\\/\\\/continentaldocs.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/continentaldocs.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"cs\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/continentaldocs.com\\\/#organization\",\"name\":\"Continental Documents Online\",\"url\":\"https:\\\/\\\/continentaldocs.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/continentaldocs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/continentaldocs.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/cropped-Gemini_Generated_Image_r4583ar4583ar458-removebg-preview-removebg-preview-1.png\",\"contentUrl\":\"https:\\\/\\\/continentaldocs.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/cropped-Gemini_Generated_Image_r4583ar4583ar458-removebg-preview-removebg-preview-1.png\",\"width\":148,\"height\":145,\"caption\":\"Continental Documents Online\"},\"image\":{\"@id\":\"https:\\\/\\\/continentaldocs.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/mydocshop\",\"https:\\\/\\\/www.pinterest.de\\\/martinnztim\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mins-koert-5a8811296\\\/\",\"https:\\\/\\\/medium.com\\\/@realdocproviders\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Certificates Archives | We Are The Best","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/continentaldocs.com\/cs\/category\/certificates\/","og_locale":"cs_CZ","og_type":"article","og_title":"Certificates Archives","og_url":"https:\/\/continentaldocs.com\/cs\/category\/certificates\/","og_site_name":"We Are The Best","og_image":[{"width":458,"height":353,"url":"https:\/\/continentaldocs.com\/wp-content\/uploads\/2024\/08\/6318f3bb-2715-455d-b41c-f730e9f53b8b.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/continentaldocs.com\/category\/certificates\/","url":"https:\/\/continentaldocs.com\/category\/certificates\/","name":"Certificates Archives | We Are The Best","isPartOf":{"@id":"https:\/\/continentaldocs.com\/#website"},"breadcrumb":{"@id":"https:\/\/continentaldocs.com\/category\/certificates\/#breadcrumb"},"inLanguage":"cs"},{"@type":"BreadcrumbList","@id":"https:\/\/continentaldocs.com\/category\/certificates\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/continentaldocs.com\/"},{"@type":"ListItem","position":2,"name":"Certificates"}]},{"@type":"WebSite","@id":"https:\/\/continentaldocs.com\/#website","url":"https:\/\/continentaldocs.com\/","name":"Continental Documents Online","description":"Continental difference is not a barrier to our services.","publisher":{"@id":"https:\/\/continentaldocs.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/continentaldocs.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"cs"},{"@type":"Organization","@id":"https:\/\/continentaldocs.com\/#organization","name":"Continental Documents Online","url":"https:\/\/continentaldocs.com\/","logo":{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/continentaldocs.com\/#\/schema\/logo\/image\/","url":"https:\/\/continentaldocs.com\/wp-content\/uploads\/2025\/10\/cropped-Gemini_Generated_Image_r4583ar4583ar458-removebg-preview-removebg-preview-1.png","contentUrl":"https:\/\/continentaldocs.com\/wp-content\/uploads\/2025\/10\/cropped-Gemini_Generated_Image_r4583ar4583ar458-removebg-preview-removebg-preview-1.png","width":148,"height":145,"caption":"Continental Documents Online"},"image":{"@id":"https:\/\/continentaldocs.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/mydocshop","https:\/\/www.pinterest.de\/martinnztim\/","https:\/\/www.linkedin.com\/in\/mins-koert-5a8811296\/","https:\/\/medium.com\/@realdocproviders"]}]}},"_links":{"self":[{"href":"https:\/\/continentaldocs.com\/cs\/wp-json\/wp\/v2\/categories\/175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/continentaldocs.com\/cs\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/continentaldocs.com\/cs\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/continentaldocs.com\/cs\/wp-json\/wp\/v2\/posts?categories=175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}